{"id":304,"date":"2017-04-03T00:00:00","date_gmt":"2017-04-03T00:00:00","guid":{"rendered":"http:\/\/dok.blog\/sem-categoria\/veja-como-tirar-a-2a-via-do-crv-de-seu-veiculo\/"},"modified":"2023-12-13T13:31:39","modified_gmt":"2023-12-13T16:31:39","slug":"como-emitir-segunda-via-de-crv","status":"publish","type":"post","link":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/","title":{"rendered":"Como emitir segunda via de CRV"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Certificado de Registro de Ve\u00edculo (CRV), tamb\u00e9m \u00e9 conhecido como \u201crecibo de compra e venda\u201d, \u00e9 um documento essencial para os ve\u00edculos. Ele \u00e9 diferente do CRLV, que \u00e9 o documento de licenciamento.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Como solicitar a 2\u00aa via CRV\" width=\"1147\" height=\"645\" src=\"https:\/\/www.youtube.com\/embed\/cr_Kl6vu2Qc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Embora n\u00e3o seja necess\u00e1rio carreg\u00e1-lo diariamente, \u00e9 preciso cuidar dele para evitar complica\u00e7\u00f5es futuras. <strong>A falta do CRV pode resultar em problemas na transfer\u00eancia<\/strong> de titularidade do ve\u00edculo.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se o CRV for perdido, ser\u00e1 necess\u00e1rio obter a segunda via para prosseguir com a compra e venda. Quer entender melhor como esse documento funciona?&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste artigo, voc\u00ea aprender\u00e1 o que \u00e9 o CRV, onde consultar, qual a diferen\u00e7a entre o CRLV e como emitir a segunda via do mesmo. <strong>Continue a leitura!<\/strong><\/p>\n\n\n\n<div class=\"tempb-app-primeiro-desktop\" id=\"tempb-665965180\"><div id=\"tempb-3638332971\"><link href=\"https:\/\/fonts.googleapis.com\/css2?family=Red+Hat+Display:wght@400;500;700&family=Inter:wght@400;500;600&display=swap\" rel=\"stylesheet\">\r\n\r\n<div style=\"width:720px;height:300px;background:#F1F3F5;border-radius:12px;overflow:hidden;position:relative;font-family:'Inter',-apple-system,BlinkMacSystemFont,sans-serif;box-shadow:0 4px 24px rgba(0,0,0,0.10);\">\r\n  <img src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2026\/06\/Vector-top-2x-desktop.png\" alt=\"\" style=\"position:absolute;top:0;right:0;width:160px;display:block;pointer-events:none;z-index:1;\">\r\n  <img src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2026\/06\/Vector-bottom-2x-desktop.png\" alt=\"\" style=\"position:absolute;bottom:0;right:110px;width:165px;display:block;pointer-events:none;z-index:1;\">\r\n  <img src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2026\/06\/Hand-and-iPhone-16-Pro-2x-desktop.png\" alt=\"App Dok no celular\" style=\"position:absolute;right:0;bottom:0;height:290px;display:block;pointer-events:none;z-index:2;\">\r\n  <div style=\"position:relative;z-index:3;padding:28px 0 28px 36px;width:500px;height:300px;display:flex;flex-direction:column;justify-content:center;gap:34px;box-sizing:border-box;\">\r\n    <div>\r\n      <div style=\"font-family:'Inter',sans-serif;font-size:15px;font-weight:400;color:#E12B2F;line-height:1.5;margin-bottom:10px;\">\r\n        Gr\u00e1tis para <span style=\"font-weight:700;\">iOS<\/span> e <span style=\"font-weight:700;text-transform:uppercase;\">Android<\/span>\r\n      <\/div>\r\n      <div style=\"font-family:'Red Hat Display',sans-serif;font-size:30px;font-weight:500;line-height:38px;color:#212529;margin-bottom:8px;\">\r\n        O <span style=\"font-weight:700;\">copiloto<\/span> do motorista brasileiro\r\n      <\/div>\r\n      <div style=\"font-family:'Inter',sans-serif;font-size:15px;font-weight:400;color:#495057;line-height:22px;\">\r\n        IPVA, multas, licenciamento e Tabela FIPE. Baixe o app Dok e consulte quando quiser, direto do celular.\r\n      <\/div>\r\n    <\/div>\r\n    <div style=\"display:flex;gap:10px;align-items:center;\">\r\n      <a href=\"https:\/\/apps.apple.com\/br\/app\/dok-despachante\/id6448805901?pt=8FND532YQ2&ct=banner_blog_app&mt=8\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"display:flex;align-items:center;gap:8px;background:#1a1a1a;color:#fff;border-radius:9px;padding:7px 14px;text-decoration:none;box-sizing:border-box;\">\r\n        <svg viewBox=\"0 0 24 24\" width=\"17\" height=\"17\" fill=\"white\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M18.71 19.5c-.83 1.24-1.71 2.45-3.05 2.47-1.34.03-1.77-.79-3.29-.79-1.53 0-2 .77-3.27.82-1.31.05-2.3-1.32-3.14-2.53C4.25 17 2.94 12.45 4.7 9.39c.87-1.52 2.43-2.48 4.12-2.51 1.28-.02 2.5.87 3.29.87.78 0 2.26-1.07 3.8-.91.65.03 2.47.26 3.64 1.98-.09.06-2.17 1.28-2.15 3.81.03 3.02 2.65 4.03 2.68 4.04-.03.07-.42 1.44-1.38 2.83M13 3.5c.73-.83 1.94-1.46 2.94-1.5.13 1.17-.34 2.35-1.04 3.19-.69.85-1.83 1.51-2.95 1.42-.15-1.15.41-2.35 1.05-3.11z\"\/><\/svg>\r\n        <div>\r\n          <div style=\"font-size:8px;opacity:0.75;line-height:1;margin-bottom:2px;font-family:'Inter',sans-serif;\">Dispon\u00edvel na<\/div>\r\n          <div style=\"font-size:13px;font-weight:600;line-height:1.2;font-family:'Inter',sans-serif;\">App Store<\/div>\r\n        <\/div>\r\n      <\/a>\r\n      <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.despachantedok.app&utm_source=blog&utm_medium=banner&utm_campaign=app\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"display:flex;align-items:center;gap:8px;background:#1a1a1a;color:#fff;border-radius:9px;padding:7px 14px;text-decoration:none;box-sizing:border-box;\">\r\n        <svg viewBox=\"0 0 24 24\" width=\"17\" height=\"17\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"#EA4335\" d=\"M3.5 21.5V2.5L14 12z\"\/><path fill=\"#FBBC04\" d=\"M14 12L20.5 8.5 3.5 2.5z\"\/><path fill=\"#34A853\" d=\"M14 12L3.5 21.5 20.5 15.5z\"\/><path fill=\"#4285F4\" d=\"M20.5 8.5L22.5 12l-2 3.5L14 12z\"\/><\/svg>\r\n        <div>\r\n          <div style=\"font-size:8px;opacity:0.75;line-height:1;margin-bottom:2px;font-family:'Inter',sans-serif;\">Dispon\u00edvel no<\/div>\r\n          <div style=\"font-size:13px;font-weight:600;line-height:1.2;font-family:'Inter',sans-serif;\">Google Play<\/div>\r\n        <\/div>\r\n      <\/a>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>\r\n<\/div><\/div><h2 class=\"wp-block-heading\" id=\"h-o-que-crv\">O que \u00e9 CRV?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ao comprar um ve\u00edculo zero quil\u00f4metro, o CRV \u00e9 expedido com base na nota fiscal do fabricante ou revendedor. O documento \u00e9 atualizado toda vez que o ve\u00edculo muda de propriet\u00e1rio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Certificado de Registro do Ve\u00edculo \u00e9 um documento indispens\u00e1vel para qualquer propriet\u00e1rio, sendo necess\u00e1rio para vender ou comprar o autom\u00f3vel.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No CRV constam algumas informa\u00e7\u00f5es como:<\/strong>&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-advgb-list\"><ul class=\"advgblist-53185464-70a4-41de-a69b-66d859d0e63e advgb-list advgb-list-controls-play\"><li>C\u00f3digo do RENAVAM;\u00a0\u00a0<\/li>\n<li>Nome do propriet\u00e1rio;\u00a0\u00a0<\/li>\n<li>N\u00famero da placa e do chassi;\u00a0<\/li>\n<li>Marca\/ modelo do ve\u00edculo;\u00a0\u00a0<\/li>\n<li>Ano de fabrica\u00e7\u00e3o.\u00a0<\/li>\n<\/ul><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Desde janeiro de 2021, <strong>a emiss\u00e3o do CRV impresso foi substitu\u00edda pela vers\u00e3o digital.<\/strong> Com isso, foi institu\u00eddo tamb\u00e9m o <a href=\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/atpv-e\/\" target=\"_blank\" rel=\"noreferrer noopener\">ATPV-e<\/a> (Autoriza\u00e7\u00e3o para Transfer\u00eancia de Propriedade do Ve\u00edculo em meio digital), que consiste no comprovante de transfer\u00eancia de propriedade.&nbsp;&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-como-consultar-informa-es-do-crv-atual-do-ve-culo\">Como consultar informa\u00e7\u00f5es do CRV atual do ve\u00edculo?&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea deseja consultar o CRV de seu ve\u00edculo, o primeiro passo \u00e9 realizar o login no <a href=\"https:\/\/portalservicos.senatran.serpro.gov.br\/#\/home\" target=\"_blank\" rel=\"noreferrer noopener\">Portal do Senatran<\/a> via gov.br, localizado no canto superior direito da sua tela.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s o login, voc\u00ea deve localizar no menu da p\u00e1gina a se\u00e7\u00e3o &#8220;Ve\u00edculos&#8221; e ent\u00e3o clicar em &#8220;Validar CRV&#8221;.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesta p\u00e1gina, voc\u00ea dever\u00e1 informar o CPF ou CNPJ do propriet\u00e1rio do ve\u00edculo, a placa, o c\u00f3digo RENAVAM do ve\u00edculo e o c\u00f3digo de seguran\u00e7a do CRV (exclusivo para documentos emitidos a partir de dezembro de 2006).&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, basta clicar em \u201cprosseguir\u201d e ser\u00e3o exibidas as <strong>informa\u00e7\u00f5es do CRV mais recente do ve\u00edculo.<\/strong>&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-emitir-segunda-via-de-crv\">Como emitir segunda via de CRV?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A segunda via do Certificado de Registro deve ser solicitada em casos de perda ou extravio do documento, bem como no momento da transfer\u00eancia do ve\u00edculo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A solicita\u00e7\u00e3o pode ser feita pelo Detran em que o ve\u00edculo est\u00e1 registrado, por meio de despachantes credenciados e, no caso de S\u00e3o Paulo, pelo Poupatempo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para a emiss\u00e3o da segunda via do CRV, <strong>\u00e9 preciso que <\/strong><a href=\"https:\/\/www.despachantedok.com.br\/segunda-via-crv\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>todos os d\u00e9bitos e impostos do ve\u00edculo estejam pagos<\/strong><\/a><strong>.<\/strong> E em alguns estados, como Minas Gerais e Rio de Janeiro, \u00e9 necess\u00e1rio preencher o formul\u00e1rio de perda e extravio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Normalmente, o Certificado de Registro do Ve\u00edculo fica pronto em at\u00e9 cinco dias \u00fateis, mas esse prazo pode variar de acordo com a situa\u00e7\u00e3o e com o local em que a emiss\u00e3o foi solicitada.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"395\" height=\"911\" src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2023\/08\/infografico-como-emitir-segunda-via-de-crv.jpeg\" alt=\"Infogr\u00e1fico sobre como emitir segunda via de CRV-DOK Despachante\" class=\"wp-image-20940\" srcset=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2023\/08\/infografico-como-emitir-segunda-via-de-crv.jpeg 395w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2023\/08\/infografico-como-emitir-segunda-via-de-crv-130x300.jpeg 130w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2023\/08\/infografico-como-emitir-segunda-via-de-crv-220x508.jpeg 220w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2023\/08\/infografico-como-emitir-segunda-via-de-crv-150x346.jpeg 150w\" sizes=\"(max-width: 395px) 100vw, 395px\" \/><figcaption>Infogr\u00e1fico feito por Bruna Florentino &#8211; DOK Despachante.<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-documentos-para-emiss-o-do-crv\">Documentos para emiss\u00e3o do CRV<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 necess\u00e1rio apresentar alguns documentos tanto para a primeira quanto para segunda emiss\u00e3o do CRV. <strong>Listaremos cada um deles a seguir.<\/strong> Confira!&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-primeira-emiss-o\">Primeira emiss\u00e3o<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">A solicita\u00e7\u00e3o do CRV, que pode ser feita direto no Detran, exige os seguintes documentos:&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-advgb-list\"><ul class=\"advgblist-79c37b84-d8cd-4fd3-b44d-7db2280b35d3 advgb-list advgb-list-arrow-right-alt\"><li>Nota fiscal do ve\u00edculo;\u00a0<\/li>\n<li>Documento de identifica\u00e7\u00e3o (RG, CNH, carteira de trabalho ou passaporte);<\/li>\n<li>Comprovante de endere\u00e7o atualizado;\u00a0<\/li>\n<li>N\u00famero do chassi do ve\u00edculo.\u00a0\u00a0<\/li>\n<\/ul><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Se preferir realizar o procedimento pela internet, \u00e9 s\u00f3 acessar o site do Detran do seu estado, preencher a solicita\u00e7\u00e3o de registro e anexar os documentos solicitados em PDF.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A an\u00e1lise da documenta\u00e7\u00e3o enviada pode levar at\u00e9 cinco dias \u00fateis. Ap\u00f3s esse prazo, ser\u00e3o encaminhadas ao propriet\u00e1rio as guias de pagamento do IPVA, do DPVAT, bem como da taxa de registro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existe tamb\u00e9m a possibilidade de realizar a emiss\u00e3o do CRV presencial do Detran. Nesse caso, o formul\u00e1rio do RENAVAM ser\u00e1 preenchido ap\u00f3s a verifica\u00e7\u00e3o da documenta\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As mesmas guias de pagamento ser\u00e3o emitidas. Ap\u00f3s a regulariza\u00e7\u00e3o dos valores, o Detran emitir\u00e1 o c\u00f3digo de seguran\u00e7a do CRV, o qual dever\u00e1 ser utilizado para fazer o licenciamento do ve\u00edculo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lembre-se:<\/strong> para fazer o processo presencial no Detran, \u00e9 necess\u00e1rio agendar um hor\u00e1rio pelo site.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ademais, a solicita\u00e7\u00e3o de registro do novo ve\u00edculo deve ser feita <strong>em at\u00e9 30 dias ap\u00f3s a emiss\u00e3o da nota fiscal.<\/strong> Caso contr\u00e1rio, o propriet\u00e1rio poder\u00e1 ser multado por atraso na regulariza\u00e7\u00e3o da documenta\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-segunda-via-de-crv\">Segunda via de CRV<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">No caso de perda, furto, m\u00e1 conserva\u00e7\u00e3o ou qualquer outro motivo que invalide a primeira via do documento, voc\u00ea pode solicitar uma segunda via de CRV.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entretanto, para isso, o ve\u00edculo <a href=\"https:\/\/www.despachantedok.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">n\u00e3o pode ter pend\u00eancias financeiras<\/a> (como multas ou IPVA atrasado), ou restri\u00e7\u00f5es, ou bloqueios administrativos e judiciais.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O pedido do novo CRV precisa ser feito no munic\u00edpio de resid\u00eancia do motorista solicitante e no estado em que o ve\u00edculo est\u00e1 registrado.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caso esteja tudo em dia, para emiss\u00e3o de um novo documento CRV \u2013 ou seja, a segunda via -, faz-se necess\u00e1rio apresentar tais documentos:&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-advgb-list\"><ul class=\"advgblist-9c181952-7cb8-4c29-aa70-58b73e8f2d02 advgb-list advgb-list-arrow-right-alt\"><li>C\u00f3pia do comprovante de endere\u00e7o do propriet\u00e1rio;\u00a0<\/li>\n<li>C\u00f3pia do documento de identifica\u00e7\u00e3o (RG, CNH, carteira de trabalho ou passaporte);\u00a0<\/li>\n<li>Laudo veicular ECV, realizado em uma empresa credenciada pelo Detran;\u00a0<\/li>\n<li>Boletim de ocorr\u00eancia, em caso de roubo ou furto;\u00a0<\/li>\n<li>Declara\u00e7\u00e3o de extravio do CRV, em caso de perda (nesse caso, \u00e9 necess\u00e1rio reconhecer firma por autenticidade).\u00a0<\/li>\n<\/ul><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ser\u00e1 necess\u00e1rio pagar uma taxa para a emiss\u00e3o em qualquer banco ou em ag\u00eancias credenciadas. Depois de cumprir todas as etapas, o documento fica dispon\u00edvel para download em at\u00e9 quatro dias uteis.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-quando-preciso-emitir-uma-segunda-via-de-crv\">Quando \u00e9 preciso emitir uma segunda via de CRV?&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Embora n\u00e3o tenha data de validade, segundo o <a href=\"https:\/\/www.ctbdigital.com.br\/artigo\/art123\" target=\"_blank\" rel=\"noreferrer noopener\">Artigo n\u00ba 123 do CTB<\/a>, a emiss\u00e3o de um novo CRV \u00e9 obrigat\u00f3ria nas seguintes situa\u00e7\u00f5es:&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-advgb-list\"><ul class=\"advgblist-0a30373f-bffe-4360-9b0e-a6816eb312d9 advgb-list advgb-list-marker\"><li>Quando for transferida a propriedade;\u00a0<\/li>\n<li>O propriet\u00e1rio mudar o munic\u00edpio ou resid\u00eancia;\u00a0<\/li>\n<li>Quando houver mudan\u00e7a de categoria;\u00a0<\/li>\n<li>Caso seja alterada qualquer caracter\u00edstica do ve\u00edculo.\u00a0<\/li>\n<\/ul><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto no caso do CRLV como para o CRV, \u00e9 necess\u00e1rio estar com todos os d\u00e9bitos do ve\u00edculo em dia para que uma nova via seja emitida.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea est\u00e1 com o IPVA atrasado ou multas pendentes, n\u00e3o deixe para depois! Regularize seus d\u00e9bitos veiculares <a href=\"https:\/\/www.despachantedok.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">aqui no DOK Despachante<\/a> em at\u00e9 12 vezes.&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-saiba-mais-sobre-documenta-o\">Saiba mais sobre Documenta\u00e7\u00e3o!&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ei, Motorista! Se voc\u00ea chegou at\u00e9 aqui, temos outros artigos que podem te interessar. Confira:<\/p>\n\n\n\n<div class=\"wp-block-advgb-list\"><ul class=\"advgblist-895219bc-e14f-401d-bcd8-d0fbd0d5b2c5 advgb-list advgb-list-admin-post\"><li><a href=\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/diferenca-crv-e-crlv\/\" target=\"_blank\" rel=\"noreferrer noopener\">Entenda a diferen\u00e7a entre CRV e CRLV<\/a>\u00a0<\/li>\n<li><a href=\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/transferencia-de-veiculos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Transfer\u00eancia de ve\u00edculo: o guia completo para fazer a sua<\/a>\u00a0<\/li>\n<li><a href=\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/atpv-e\/\" target=\"_blank\" rel=\"noreferrer noopener\">ATPV-e: saiba como fazer de forma digital<\/a>\u00a0<\/li>\n<\/ul><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-diferen-a-entre-crv-e-crlv\">Diferen\u00e7a entre CRV e CRLV<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Diferentemente do CRV, o Certificado de Registro e Licenciamento de Ve\u00edculos (CRLV) \u00e9 o documento que comprova que o ve\u00edculo cumpriu com as obriga\u00e7\u00f5es legais, como pagamento de impostos e multas, para circular nas vias p\u00fablicas.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele tamb\u00e9m <strong>\u00e9 conhecido como licenciamento<\/strong> e precisa ser renovado anualmente para evitar a apreens\u00e3o do ve\u00edculo.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A falta do CRLV impede a circula\u00e7\u00e3o legal do ve\u00edculo. <a href=\"https:\/\/www.despachantedok.com.br\/blog\/licenciamento\/licenciamento-de-carro\/\" target=\"_blank\" rel=\"noreferrer noopener\">O processo de licenciamento pode ser feito online<\/a>, em que o motorista paga as taxas e tributos estaduais como IPVA, DPVAT e multas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 importante entender a diferen\u00e7a entre CRV e CRLV para garantir que <strong>ambos os documentos estejam em dia,<\/strong>&nbsp; <a href=\"https:\/\/www.despachantedok.com.br\/licenciamento-online\" target=\"_blank\" rel=\"noreferrer noopener\">evitar complica\u00e7\u00f5es legais<\/a> e a circula\u00e7\u00e3o irregular do ve\u00edculo.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quanto-custa-a-segunda-via-de-crv\">Quanto custa a segunda via de CRV?&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para a segunda via do CRV, caso o licenciamento do ve\u00edculo esteja em dia, \u00e9 necess\u00e1rio pagar uma taxa de emiss\u00e3o de R$ 246,17 (ou de R$ 391,03, se o licenciamento estiver pendente).&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclus-o\">Conclus\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea n\u00e3o quer lidar com as burocracias das leis de tr\u00e2nsito, saiba que \u00e9 poss\u00edvel fazer a solicita\u00e7\u00e3o da segunda via do CRV com o DOK Despachante!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m de confi\u00e1vel, o DOK oferece uma solu\u00e7\u00e3o completa para consultas, pagamentos e parcelamentos de d\u00e9bitos veiculares, tornando o processo mais pr\u00e1tico e seguro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pensando sempre no cliente, o DOK disponibiliza as melhores formas de pagamento, podendo parcelar em 12 vezes com at\u00e9 seis diferentes cart\u00f5es de cr\u00e9dito.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gostou do conte\u00fado? Em <a href=\"https:\/\/www.despachantedok.com.br\/blog\/\" target=\"_blank\" rel=\"noreferrer noopener\">nosso blog<\/a> temos uma diversidade de conte\u00fado para todas as suas d\u00favidas! Tamb\u00e9m confira os conte\u00fados das nossas redes sociais. Estamos no <a href=\"https:\/\/www.instagram.com\/dokdespachante\/?__coig_restricted=1\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>, <a href=\"https:\/\/web.facebook.com\/DOKDespachante?_rdc=1&amp;_rdr\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>, <a href=\"https:\/\/www.youtube.com\/@DOKDespachanteOficial\" target=\"_blank\" rel=\"noreferrer noopener\">YouTube<\/a>, <a href=\"https:\/\/www.tiktok.com\/@despachantedok\" target=\"_blank\" rel=\"noreferrer noopener\">TikTok<\/a> e <a href=\"https:\/\/br.linkedin.com\/company\/despachantedok\" target=\"_blank\" rel=\"noreferrer noopener\">LinkedIn<\/a>.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"650\" height=\"27\" src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2023\/07\/separador-h2.png\" alt=\"separador | DOK Despachante\" class=\"wp-image-20614\" srcset=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2023\/07\/separador-h2.png.jpg 650w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2023\/07\/separador-h2.png-300x188.png 300w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2023\/07\/separador-h2.png 640w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2023\/07\/separador-h2.png 150w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-perguntas-frequentes-sobre-crv\">Perguntas frequentes sobre CRV&nbsp;<\/h2>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1692896040587\"><strong class=\"schema-faq-question\"><strong>Eu posso ser multado(a) se n\u00e3o estiver portando o CRV?<\/strong>\u00a0<\/strong> <p class=\"schema-faq-answer\">N\u00e3o. O porte do CRV n\u00e3o \u00e9 obrigat\u00f3rio em territ\u00f3rio nacional. Por isso, caso seja parado, o agente ou policial n\u00e3o pode exigir que voc\u00ea apresente esse documento.\u00a0\u00a0<br\/>Mas, apesar de n\u00e3o ser necess\u00e1rio portar o documento, \u00e9 importante refor\u00e7ar que ele deve estar em dia, de todo modo.\u00a0<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1692896068848\"><strong class=\"schema-faq-question\"><strong>O CRV \u00e9 obrigat\u00f3rio?<\/strong>\u00a0<\/strong> <p class=\"schema-faq-answer\">Sim. O CRV \u00e9 obrigat\u00f3rio para todos os ve\u00edculos brasileiros. Caso n\u00e3o registre o autom\u00f3vel, voc\u00ea ser\u00e1 proibido de circular em vias p\u00fablicas. O mesmo se aplica \u00e0s motos ou quaisquer outros meios de transporte rodovi\u00e1rios.\u00a0\u00a0<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1692896085418\"><strong class=\"schema-faq-question\"><strong>O que \u00e9 o CRV digital?<\/strong>\u00a0<\/strong> <p class=\"schema-faq-answer\">O CRV digital \u00e9 a vers\u00e3o eletr\u00f4nica do Certificado de Registro de Ve\u00edculo, permitindo que as informa\u00e7\u00f5es do ve\u00edculo sejam acessadas online, agilizando processos e reduzindo o desperd\u00edcio de papel.<\/p> <\/div> <\/div>\n<style class=\"advgb-styles-renderer\">.wp-block-advgb-list ul.advgblist-53185464-70a4-41de-a69b-66d859d0e63e > li{font-size:17px;}.wp-block-advgb-list ul.advgblist-53185464-70a4-41de-a69b-66d859d0e63e > li{padding-left:18px;margin-left:0;}.wp-block-advgb-list ul.advgblist-53185464-70a4-41de-a69b-66d859d0e63e > li:before{font-size:16px;color:#ff0000;line-height:25px;margin:2px;padding:2px;margin-left:-20px}.wp-block-advgb-list ul.advgblist-79c37b84-d8cd-4fd3-b44d-7db2280b35d3 > li{font-size:17px;}.wp-block-advgb-list ul.advgblist-79c37b84-d8cd-4fd3-b44d-7db2280b35d3 > li{padding-left:18px;margin-left:0;}.wp-block-advgb-list ul.advgblist-79c37b84-d8cd-4fd3-b44d-7db2280b35d3 > li:before{font-size:16px;color:#ff0000;line-height:25px;margin:2px;padding:2px;margin-left:-20px}.wp-block-advgb-list ul.advgblist-9c181952-7cb8-4c29-aa70-58b73e8f2d02 > li{font-size:17px;}.wp-block-advgb-list ul.advgblist-9c181952-7cb8-4c29-aa70-58b73e8f2d02 > li{padding-left:18px;margin-left:0;}.wp-block-advgb-list ul.advgblist-9c181952-7cb8-4c29-aa70-58b73e8f2d02 > li:before{font-size:16px;color:#ff0000;line-height:30px;margin:2px;padding:2px;margin-left:-20px}.wp-block-advgb-list ul.advgblist-0a30373f-bffe-4360-9b0e-a6816eb312d9 > li{font-size:17px;}.wp-block-advgb-list ul.advgblist-0a30373f-bffe-4360-9b0e-a6816eb312d9 > li{padding-left:18px;margin-left:0;}.wp-block-advgb-list ul.advgblist-0a30373f-bffe-4360-9b0e-a6816eb312d9 > li:before{font-size:16px;color:#ff0000;line-height:25px;margin:2px;padding:2px;margin-left:-20px}.wp-block-advgb-list ul.advgblist-895219bc-e14f-401d-bcd8-d0fbd0d5b2c5 > li{font-size:17px;}.wp-block-advgb-list ul.advgblist-895219bc-e14f-401d-bcd8-d0fbd0d5b2c5 > li{padding-left:18px;margin-left:0;}.wp-block-advgb-list ul.advgblist-895219bc-e14f-401d-bcd8-d0fbd0d5b2c5 > li:before{font-size:16px;color:#ff0000;line-height:25px;margin:2px;padding:2px;margin-left:-20px}<\/style>","protected":false},"excerpt":{"rendered":"<p>Perdeu o CRV? Sem problemas! Veja como tirar sua segunda via sem dor de cabe\u00e7a.<\/p>\n","protected":false},"author":9,"featured_media":20941,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_title":"Como emitir segunda via de CRV | DOK Despachante","_yoast_wpseo_metadesc":"O CRV funciona como o recibo do ve\u00edculo, e \u00e9 essencial para a emiss\u00e3o de outros documentos veiculares como o licenciamento. Entenda tudo sobre o CRV neste blog!","advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_glsr_average":3.8,"_glsr_ranking":3.65,"_glsr_reviews":10,"lazy_load_responsive_images_disabled":false,"footnotes":""},"categories":[139],"tags":[],"class_list":["post-304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Como emitir segunda via de CRV | DOK Despachante<\/title>\n<meta name=\"description\" content=\"O CRV funciona como o recibo do ve\u00edculo, e \u00e9 essencial para a emiss\u00e3o de outros documentos veiculares como o licenciamento. Entenda tudo sobre o CRV neste blog!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como emitir segunda via de CRV\" \/>\n<meta property=\"og:description\" content=\"O CRV funciona como o recibo do ve\u00edculo, e \u00e9 essencial para a emiss\u00e3o de outros documentos veiculares como o licenciamento. Entenda tudo sobre o CRV neste blog!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/\" \/>\n<meta property=\"og:site_name\" content=\"Acesse o Blog e conhe\u00e7a todos os nossos artigos | DOK Despachante\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/DOKDespachante\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-03T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-13T16:31:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2017\/04\/capa-como-emitir-segunda-via-de-crv.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"254\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gregory Packs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gregory Packs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/\"},\"author\":{\"name\":\"Gregory Packs\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/person\/6e41d0c1afe01aefd76c3ee23f914fea\"},\"headline\":\"Como emitir segunda via de CRV\",\"datePublished\":\"2017-04-03T00:00:00+00:00\",\"dateModified\":\"2023-12-13T16:31:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/\"},\"wordCount\":1701,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2017\/04\/capa-como-emitir-segunda-via-de-crv.jpeg\",\"articleSection\":[\"Documenta\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#organization\"}},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/\",\"url\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/\",\"name\":\"Como emitir segunda via de CRV | DOK Despachante\",\"isPartOf\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2017\/04\/capa-como-emitir-segunda-via-de-crv.jpeg\",\"datePublished\":\"2017-04-03T00:00:00+00:00\",\"dateModified\":\"2023-12-13T16:31:39+00:00\",\"description\":\"O CRV funciona como o recibo do ve\u00edculo, e \u00e9 essencial para a emiss\u00e3o de outros documentos veiculares como o licenciamento. Entenda tudo sobre o CRV neste blog!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896040587\"},{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896068848\"},{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896085418\"}],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#primaryimage\",\"url\":\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2017\/04\/capa-como-emitir-segunda-via-de-crv.jpeg\",\"contentUrl\":\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2017\/04\/capa-como-emitir-segunda-via-de-crv.jpeg\",\"width\":555,\"height\":254},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.despachantedok.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documenta\u00e7\u00e3o\",\"item\":\"https:\/\/www.despachantedok.com.br\/blog\/categoria\/documentacao\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Como emitir segunda via de CRV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#website\",\"url\":\"https:\/\/www.despachantedok.com.br\/blog\/\",\"name\":\"Not\u00edcias e informa\u00e7\u00f5es do universo veicular - Blog do Dok\",\"description\":\"Fique por dentro de artigos sobre o tr\u00e2nsito brasileiro! Conhe\u00e7a informa\u00e7\u00f5es sobre licenciamento, ipva, multas e muito mais. Acesse agora o Blog do DOK!\",\"publisher\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#organization\"},\"alternateName\":\"Blog do Dok\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.despachantedok.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#organization\",\"name\":\"Dok Despachante\",\"alternateName\":\"Dok\",\"url\":\"https:\/\/www.despachantedok.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/01\/logo-dok_novo_blog.svg\",\"contentUrl\":\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/01\/logo-dok_novo_blog.svg\",\"width\":284,\"height\":131,\"caption\":\"Dok Despachante\"},\"image\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/DOKDespachante\/\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Pra\u00e7a Frank Speers, 12\",\"addressLocality\":\"Sorocaba\",\"addressRegion\":\"SP\",\"postalCode\":\"18095-020\",\"addressCountry\":\"BR\"},\"email\":\"fale@despachantedok.com.br\",\"telephone\":\"551530422030\",\"legalName\":\"DOK Servi\u00e7os de Pagamentos Ltda.\",\"vatID\":\"27.838.743\/0001-91\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/person\/6e41d0c1afe01aefd76c3ee23f914fea\",\"name\":\"Gregory Packs\",\"description\":\"Formado em An\u00e1lise de Sistemas e Marketing Digital, Gregory Packs \u00e9 o fundador do DOK Despachante, o primeiro despachante online do estado de S\u00e3o Paulo. Com uma vis\u00e3o inovadora, ele revolucionou a maneira que as pessoas fazem seus documentos veiculares, disponibilizando uma plataforma 100% online que facilita e agiliza esse processo, oferecendo diversos servi\u00e7os de forma simples, segura e eficiente, como consulta e pagamento de licenciamento, IPVA, multas, entre outros. Atualmente, o DOK j\u00e1 atendeu mais de 200 mil motoristas e est\u00e1 sempre em busca de oferecer os melhores servi\u00e7os e experi\u00eancia aos seus clientes.\u00a0\",\"url\":\"https:\/\/www.despachantedok.com.br\/blog\/author\/gregory\/\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896040587\",\"position\":1,\"url\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896040587\",\"name\":\"Eu posso ser multado(a) se n\u00e3o estiver portando o CRV?\u00a0\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"N\u00e3o. O porte do CRV n\u00e3o \u00e9 obrigat\u00f3rio em territ\u00f3rio nacional. Por isso, caso seja parado, o agente ou policial n\u00e3o pode exigir que voc\u00ea apresente esse documento.\u00a0\u00a0<br\/>Mas, apesar de n\u00e3o ser necess\u00e1rio portar o documento, \u00e9 importante refor\u00e7ar que ele deve estar em dia, de todo modo.\u00a0\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896068848\",\"position\":2,\"url\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896068848\",\"name\":\"O CRV \u00e9 obrigat\u00f3rio?\u00a0\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Sim. O CRV \u00e9 obrigat\u00f3rio para todos os ve\u00edculos brasileiros. Caso n\u00e3o registre o autom\u00f3vel, voc\u00ea ser\u00e1 proibido de circular em vias p\u00fablicas. O mesmo se aplica \u00e0s motos ou quaisquer outros meios de transporte rodovi\u00e1rios.\u00a0\u00a0\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896085418\",\"position\":3,\"url\":\"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896085418\",\"name\":\"O que \u00e9 o CRV digital?\u00a0\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"O CRV digital \u00e9 a vers\u00e3o eletr\u00f4nica do Certificado de Registro de Ve\u00edculo, permitindo que as informa\u00e7\u00f5es do ve\u00edculo sejam acessadas online, agilizando processos e reduzindo o desperd\u00edcio de papel.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Como emitir segunda via de CRV | DOK Despachante","description":"O CRV funciona como o recibo do ve\u00edculo, e \u00e9 essencial para a emiss\u00e3o de outros documentos veiculares como o licenciamento. Entenda tudo sobre o CRV neste blog!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/","og_locale":"pt_BR","og_type":"article","og_title":"Como emitir segunda via de CRV","og_description":"O CRV funciona como o recibo do ve\u00edculo, e \u00e9 essencial para a emiss\u00e3o de outros documentos veiculares como o licenciamento. Entenda tudo sobre o CRV neste blog!","og_url":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/","og_site_name":"Acesse o Blog e conhe\u00e7a todos os nossos artigos | DOK Despachante","article_publisher":"https:\/\/facebook.com\/DOKDespachante\/","article_published_time":"2017-04-03T00:00:00+00:00","article_modified_time":"2023-12-13T16:31:39+00:00","og_image":[{"width":555,"height":254,"url":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2017\/04\/capa-como-emitir-segunda-via-de-crv.jpeg","type":"image\/jpeg"}],"author":"Gregory Packs","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gregory Packs","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#article","isPartOf":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/"},"author":{"name":"Gregory Packs","@id":"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/person\/6e41d0c1afe01aefd76c3ee23f914fea"},"headline":"Como emitir segunda via de CRV","datePublished":"2017-04-03T00:00:00+00:00","dateModified":"2023-12-13T16:31:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/"},"wordCount":1701,"commentCount":0,"publisher":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2017\/04\/capa-como-emitir-segunda-via-de-crv.jpeg","articleSection":["Documenta\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/#organization"}},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/","url":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/","name":"Como emitir segunda via de CRV | DOK Despachante","isPartOf":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#primaryimage"},"image":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2017\/04\/capa-como-emitir-segunda-via-de-crv.jpeg","datePublished":"2017-04-03T00:00:00+00:00","dateModified":"2023-12-13T16:31:39+00:00","description":"O CRV funciona como o recibo do ve\u00edculo, e \u00e9 essencial para a emiss\u00e3o de outros documentos veiculares como o licenciamento. Entenda tudo sobre o CRV neste blog!","breadcrumb":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896040587"},{"@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896068848"},{"@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896085418"}],"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#primaryimage","url":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2017\/04\/capa-como-emitir-segunda-via-de-crv.jpeg","contentUrl":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2017\/04\/capa-como-emitir-segunda-via-de-crv.jpeg","width":555,"height":254},{"@type":"BreadcrumbList","@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.despachantedok.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Documenta\u00e7\u00e3o","item":"https:\/\/www.despachantedok.com.br\/blog\/categoria\/documentacao\/"},{"@type":"ListItem","position":3,"name":"Como emitir segunda via de CRV"}]},{"@type":"WebSite","@id":"https:\/\/www.despachantedok.com.br\/blog\/#website","url":"https:\/\/www.despachantedok.com.br\/blog\/","name":"Not\u00edcias e informa\u00e7\u00f5es do universo veicular - Blog do Dok","description":"Fique por dentro de artigos sobre o tr\u00e2nsito brasileiro! Conhe\u00e7a informa\u00e7\u00f5es sobre licenciamento, ipva, multas e muito mais. Acesse agora o Blog do DOK!","publisher":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/#organization"},"alternateName":"Blog do Dok","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.despachantedok.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.despachantedok.com.br\/blog\/#organization","name":"Dok Despachante","alternateName":"Dok","url":"https:\/\/www.despachantedok.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/01\/logo-dok_novo_blog.svg","contentUrl":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/01\/logo-dok_novo_blog.svg","width":284,"height":131,"caption":"Dok Despachante"},"image":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/DOKDespachante\/"],"address":{"@type":"PostalAddress","streetAddress":"Pra\u00e7a Frank Speers, 12","addressLocality":"Sorocaba","addressRegion":"SP","postalCode":"18095-020","addressCountry":"BR"},"email":"fale@despachantedok.com.br","telephone":"551530422030","legalName":"DOK Servi\u00e7os de Pagamentos Ltda.","vatID":"27.838.743\/0001-91"},{"@type":"Person","@id":"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/person\/6e41d0c1afe01aefd76c3ee23f914fea","name":"Gregory Packs","description":"Formado em An\u00e1lise de Sistemas e Marketing Digital, Gregory Packs \u00e9 o fundador do DOK Despachante, o primeiro despachante online do estado de S\u00e3o Paulo. Com uma vis\u00e3o inovadora, ele revolucionou a maneira que as pessoas fazem seus documentos veiculares, disponibilizando uma plataforma 100% online que facilita e agiliza esse processo, oferecendo diversos servi\u00e7os de forma simples, segura e eficiente, como consulta e pagamento de licenciamento, IPVA, multas, entre outros. Atualmente, o DOK j\u00e1 atendeu mais de 200 mil motoristas e est\u00e1 sempre em busca de oferecer os melhores servi\u00e7os e experi\u00eancia aos seus clientes.\u00a0","url":"https:\/\/www.despachantedok.com.br\/blog\/author\/gregory\/"},{"@type":"Question","@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896040587","position":1,"url":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896040587","name":"Eu posso ser multado(a) se n\u00e3o estiver portando o CRV?\u00a0","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"N\u00e3o. O porte do CRV n\u00e3o \u00e9 obrigat\u00f3rio em territ\u00f3rio nacional. Por isso, caso seja parado, o agente ou policial n\u00e3o pode exigir que voc\u00ea apresente esse documento.\u00a0\u00a0<br\/>Mas, apesar de n\u00e3o ser necess\u00e1rio portar o documento, \u00e9 importante refor\u00e7ar que ele deve estar em dia, de todo modo.\u00a0","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896068848","position":2,"url":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896068848","name":"O CRV \u00e9 obrigat\u00f3rio?\u00a0","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Sim. O CRV \u00e9 obrigat\u00f3rio para todos os ve\u00edculos brasileiros. Caso n\u00e3o registre o autom\u00f3vel, voc\u00ea ser\u00e1 proibido de circular em vias p\u00fablicas. O mesmo se aplica \u00e0s motos ou quaisquer outros meios de transporte rodovi\u00e1rios.\u00a0\u00a0","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896085418","position":3,"url":"https:\/\/www.despachantedok.com.br\/blog\/documentacao\/como-emitir-segunda-via-de-crv\/#faq-question-1692896085418","name":"O que \u00e9 o CRV digital?\u00a0","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"O CRV digital \u00e9 a vers\u00e3o eletr\u00f4nica do Certificado de Registro de Ve\u00edculo, permitindo que as informa\u00e7\u00f5es do ve\u00edculo sejam acessadas online, agilizando processos e reduzindo o desperd\u00edcio de papel.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"}]}},"author_meta":{"display_name":"Gregory Packs","author_link":"https:\/\/www.despachantedok.com.br\/blog\/author\/gregory\/"},"featured_img":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2017\/04\/capa-como-emitir-segunda-via-de-crv-300x137.jpeg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.despachantedok.com.br\/blog\/categoria\/documentacao\/\" class=\"advgb-post-tax-term\">Documenta\u00e7\u00e3o<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Documenta\u00e7\u00e3o<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 9 anos atr\u00e1s","modified":"Atualizado 3 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em abril 3, 2017","modified":"Atualizado em dezembro 13, 2023"},"absolute_dates_time":{"created":"Publicado em abril 3, 2017 12:00 am","modified":"Atualizado em dezembro 13, 2023 1:31 pm"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/posts\/304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/comments?post=304"}],"version-history":[{"count":12,"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/posts\/304\/revisions"}],"predecessor-version":[{"id":22466,"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/posts\/304\/revisions\/22466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/media\/20941"}],"wp:attachment":[{"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/media?parent=304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/categories?post=304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/tags?post=304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}