{"id":27530,"date":"2024-06-10T14:02:31","date_gmt":"2024-06-10T17:02:31","guid":{"rendered":"https:\/\/www.despachantedok.com.br\/blog\/?p=27530"},"modified":"2024-06-10T14:02:33","modified_gmt":"2024-06-10T17:02:33","slug":"carros-da-volkswagen","status":"publish","type":"post","link":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/","title":{"rendered":"Carros da Volkswagen: entre cl\u00e1ssicos e lan\u00e7amentos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Salve, Motorista! Os carros da Volkswagen s\u00e3o uma mistura \u00fanica de tradi\u00e7\u00e3o e inova\u00e7\u00e3o. Com um legado de oito d\u00e9cadas na ind\u00fastria automotiva, a Volkswagen se consolidou como uma das maiores montadoras do planeta.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seus cl\u00e1ssicos modelos que moldaram a hist\u00f3ria da marca, at\u00e9 os mais recentes lan\u00e7amentos, continuam a surpreender e encantar entusiastas e motoristas em todo o mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Continue a leitura e conhe\u00e7a o passado, o presente e o futuro dos carros da Volkswagen!<\/p>\n\n\n\n<div class=\"tempb-app-primeiro-desktop\" id=\"tempb-1423847687\"><div id=\"tempb-475361300\"><link href=\"https:\/\/fonts.googleapis.com\/css2?family=Red+Hat+Display:wght@400;500;700&family=Inter:wght@400;500;600&display=swap\" rel=\"stylesheet\">\r\n\r\n<div style=\"width:720px;height:300px;background:#F1F3F5;border-radius:12px;overflow:hidden;position:relative;font-family:'Inter',-apple-system,BlinkMacSystemFont,sans-serif;box-shadow:0 4px 24px rgba(0,0,0,0.10);\">\r\n  <img src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2026\/06\/Vector-top-2x-desktop.png\" alt=\"\" style=\"position:absolute;top:0;right:0;width:160px;display:block;pointer-events:none;z-index:1;\">\r\n  <img src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2026\/06\/Vector-bottom-2x-desktop.png\" alt=\"\" style=\"position:absolute;bottom:0;right:110px;width:165px;display:block;pointer-events:none;z-index:1;\">\r\n  <img src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2026\/06\/Hand-and-iPhone-16-Pro-2x-desktop.png\" alt=\"App Dok no celular\" style=\"position:absolute;right:0;bottom:0;height:290px;display:block;pointer-events:none;z-index:2;\">\r\n  <div style=\"position:relative;z-index:3;padding:28px 0 28px 36px;width:500px;height:300px;display:flex;flex-direction:column;justify-content:center;gap:34px;box-sizing:border-box;\">\r\n    <div>\r\n      <div style=\"font-family:'Inter',sans-serif;font-size:15px;font-weight:400;color:#E12B2F;line-height:1.5;margin-bottom:10px;\">\r\n        Gr\u00e1tis para <span style=\"font-weight:700;\">iOS<\/span> e <span style=\"font-weight:700;text-transform:uppercase;\">Android<\/span>\r\n      <\/div>\r\n      <div style=\"font-family:'Red Hat Display',sans-serif;font-size:30px;font-weight:500;line-height:38px;color:#212529;margin-bottom:8px;\">\r\n        O <span style=\"font-weight:700;\">copiloto<\/span> do motorista brasileiro\r\n      <\/div>\r\n      <div style=\"font-family:'Inter',sans-serif;font-size:15px;font-weight:400;color:#495057;line-height:22px;\">\r\n        IPVA, multas, licenciamento e Tabela FIPE. Baixe o app Dok e consulte quando quiser, direto do celular.\r\n      <\/div>\r\n    <\/div>\r\n    <div style=\"display:flex;gap:10px;align-items:center;\">\r\n      <a href=\"https:\/\/apps.apple.com\/br\/app\/dok-despachante\/id6448805901?pt=8FND532YQ2&ct=banner_blog_app&mt=8\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"display:flex;align-items:center;gap:8px;background:#1a1a1a;color:#fff;border-radius:9px;padding:7px 14px;text-decoration:none;box-sizing:border-box;\">\r\n        <svg viewBox=\"0 0 24 24\" width=\"17\" height=\"17\" fill=\"white\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M18.71 19.5c-.83 1.24-1.71 2.45-3.05 2.47-1.34.03-1.77-.79-3.29-.79-1.53 0-2 .77-3.27.82-1.31.05-2.3-1.32-3.14-2.53C4.25 17 2.94 12.45 4.7 9.39c.87-1.52 2.43-2.48 4.12-2.51 1.28-.02 2.5.87 3.29.87.78 0 2.26-1.07 3.8-.91.65.03 2.47.26 3.64 1.98-.09.06-2.17 1.28-2.15 3.81.03 3.02 2.65 4.03 2.68 4.04-.03.07-.42 1.44-1.38 2.83M13 3.5c.73-.83 1.94-1.46 2.94-1.5.13 1.17-.34 2.35-1.04 3.19-.69.85-1.83 1.51-2.95 1.42-.15-1.15.41-2.35 1.05-3.11z\"\/><\/svg>\r\n        <div>\r\n          <div style=\"font-size:8px;opacity:0.75;line-height:1;margin-bottom:2px;font-family:'Inter',sans-serif;\">Dispon\u00edvel na<\/div>\r\n          <div style=\"font-size:13px;font-weight:600;line-height:1.2;font-family:'Inter',sans-serif;\">App Store<\/div>\r\n        <\/div>\r\n      <\/a>\r\n      <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.despachantedok.app&utm_source=blog&utm_medium=banner&utm_campaign=app\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"display:flex;align-items:center;gap:8px;background:#1a1a1a;color:#fff;border-radius:9px;padding:7px 14px;text-decoration:none;box-sizing:border-box;\">\r\n        <svg viewBox=\"0 0 24 24\" width=\"17\" height=\"17\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"#EA4335\" d=\"M3.5 21.5V2.5L14 12z\"\/><path fill=\"#FBBC04\" d=\"M14 12L20.5 8.5 3.5 2.5z\"\/><path fill=\"#34A853\" d=\"M14 12L3.5 21.5 20.5 15.5z\"\/><path fill=\"#4285F4\" d=\"M20.5 8.5L22.5 12l-2 3.5L14 12z\"\/><\/svg>\r\n        <div>\r\n          <div style=\"font-size:8px;opacity:0.75;line-height:1;margin-bottom:2px;font-family:'Inter',sans-serif;\">Dispon\u00edvel no<\/div>\r\n          <div style=\"font-size:13px;font-weight:600;line-height:1.2;font-family:'Inter',sans-serif;\">Google Play<\/div>\r\n        <\/div>\r\n      <\/a>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>\r\n<\/div><\/div><h2 class=\"wp-block-heading\" id=\"h-um-pouco-da-hist-ria-da-volkswagen\">Um pouco da hist\u00f3ria da Volkswagen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A Volkswagen, marca alem\u00e3 com mais oitenta anos de hist\u00f3ria, \u00e9 um dos nomes mais renomados da ind\u00fastria automotiva global. Sua trajet\u00f3ria teve inicio no contexto da Alemanha Nazista, com o lan\u00e7amento do popular \u201cCarro do Povo\u201d. J\u00e1 sabe de qual carro estamos falando, Motorista? Continue a leitura e descubra mais adiante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nas d\u00e9cadas seguintes, a Volkswagen se firmou como uma das maiores fabricantes de autom\u00f3veis do mundo, exemplo de engenhosidade, adaptabilidade e inova\u00e7\u00e3o. Modelos como Gol, <a href=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/volkswagen-voyage\" target=\"_blank\" rel=\"noreferrer noopener\">Voyage<\/a>, Santana, <a href=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/volkswagen-fox\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fox<\/a> e Kombi se tornaram \u00edcones em v\u00e1rios pa\u00edses, conhecidos por sua confiabilidade, economia e dirigibilidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a Volkswagen foi a primeira fabricante de autom\u00f3veis a aderir ao Acordo de Paris, comprometendo-se a ser neutra em emiss\u00f5es de carbono at\u00e9 2050.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A marca tamb\u00e9m explorou novos segmentos, como SUVs com o Tiguan, e se destacou em carros premium com modelos como Jetta, Passat e Audi, atendendo a um p\u00fablico mais exigente que busca requinte, tecnologia e desempenho.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-modelos-inesquec-veis-carros-antigos-e-cl-ssicos-da-volkswagen\">Modelos inesquec\u00edveis: carros antigos e cl\u00e1ssicos da Volkswagen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ao longo dos anos, a Volkswagen presenteou o mundo com diversos modelos que marcaram \u00e9poca, cada um com suas caracter\u00edsticas \u00fanicas que conquistaram o cora\u00e7\u00e3o do p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confira a lista dos carros da Volkswagen mais ic\u00f4nicos e inesquec\u00edveis:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-fusca\">Fusca<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Conhecido como o \u201cCarro do Povo\u201d, o Fusca foi um modelo da Volkswagen que transcendeu gera\u00e7\u00f5es, com seu design simp\u00e1tico, confiabilidade mec\u00e2nica e pre\u00e7o acess\u00edvel.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <a href=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/volkswagen-fusca\/\" target=\"_blank\" rel=\"noreferrer noopener\">VW Fusca<\/a>, ou \u201cBeetle\u201d, como era conhecido internacionalmente, rapidamente se tornou um s\u00edmbolo mundial, vendendo mais de 22 milh\u00f5es de unidades, marcando a cultura popular em diversos pa\u00edses e reunindo uma legi\u00e3o de f\u00e3s do ve\u00edculo, n\u00e3o s\u00f3 em tamanho real, mas tamb\u00e9m em <a href=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/hot-wheels-carros-brasileiros\/\" target=\"_blank\" rel=\"noreferrer noopener\">miniaturas Hot Wheels<\/a>.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-kathleen-brooks-1967-annie-beetle-small-dok.jpg\" alt=\"Foto de Fusca (Beetle) | DOK\" class=\"wp-image-27531\" srcset=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-kathleen-brooks-1967-annie-beetle-small-dok.jpg 850w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-kathleen-brooks-1967-annie-beetle-small-dok-300x200.jpg 300w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-kathleen-brooks-1967-annie-beetle-small-dok-768x512.jpg 768w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-kathleen-brooks-1967-annie-beetle-small-dok-762x508.jpg 762w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><figcaption>Reprodu\u00e7\u00e3o Karvi<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-gol\">Gol<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O <a href=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/volkswagen-gol\/\" target=\"_blank\" rel=\"noreferrer noopener\">VW Gol<\/a>, um dos carros mais emblem\u00e1ticos da ind\u00fastria automotiva brasileira, marcou gera\u00e7\u00f5es com sua versatilidade e confiabilidade. Desde seu lan\u00e7amento em 1980, tornou-se o queridinho do mercado, oferecendo <a href=\"https:\/\/www.despachantedok.com.br\/blog\/dicas\/carros-economicos\/\" target=\"_blank\" rel=\"noreferrer noopener\">economia,<\/a> estilo e praticidade.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com seu design ic\u00f4nico e desempenho \u00e1gil, o Gol conquistou o cora\u00e7\u00e3o dos brasileiros, tornando-se um verdadeiro s\u00edmbolo de mobilidade no pa\u00eds, mas que infelizmente <a href=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/gol-sai-de-linha\/\" target=\"_blank\" rel=\"noreferrer noopener\">saiu de linha em 2023<\/a>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-volkswagen-gol-2023-dok.jpg\" alt=\"Foto de Gol | DOK\" class=\"wp-image-27532\" srcset=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-volkswagen-gol-2023-dok.jpg 1280w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-volkswagen-gol-2023-dok-300x225.jpg 300w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-volkswagen-gol-2023-dok-1024x768.jpg 1024w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-volkswagen-gol-2023-dok-768x576.jpg 768w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-volkswagen-gol-2023-dok-677x508.jpg 677w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><figcaption>Reprodu\u00e7\u00e3o Autoo<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-kombi\">Kombi<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00edmbolo da liberdade e da aventura, a Kombi foi amada por fam\u00edlias, feirantes, viajantes e surfistas que buscavam um ve\u00edculo espa\u00e7oso e vers\u00e1til para o trabalho ou explorar o mundo \u2013 e at\u00e9 mesmo servindo como <a href=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/motorhome-4x4\/\" target=\"_blank\" rel=\"noreferrer noopener\">casa sobre rodas<\/a> para muitos aventureiros. Com certeza foi um dos ve\u00edculos mais queridos do Brasil e agora retorna em sua vers\u00e3o el\u00e9trica ao cat\u00e1logo da montadora.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-kombi-eletrica-dok.jpg\" alt=\"Foto de Kombi | DOK\" class=\"wp-image-27533\" width=\"623\" height=\"350\" srcset=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-kombi-eletrica-dok.jpg 1280w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-kombi-eletrica-dok-300x169.jpg 300w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-kombi-eletrica-dok-1024x576.jpg 1024w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-kombi-eletrica-dok-768x432.jpg 768w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-kombi-eletrica-dok-903x508.jpg 903w\" sizes=\"(max-width: 623px) 100vw, 623px\" \/><figcaption>Reprodu\u00e7\u00e3o InsideEVs Brasil<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-passat\">Passat<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O Passat foi <a href=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/sedan-ou-hatch\/\" target=\"_blank\" rel=\"noreferrer noopener\">sedan<\/a> sofisticado que conquistou as ruas a partir de 1973. Esse VW sempre ofereceu conforto, tecnologia de ponta e desempenho impec\u00e1vel, agradando a um p\u00fablico exigente que buscava um carro premium com um design atemporal.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1\"><ul class=\"blocks-gallery-grid is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"631\" height=\"420\" src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-novo-passat-dok.jpg\" alt=\"\" data-id=\"27534\" data-link=\"https:\/\/www.despachantedok.com.br\/blog\/?attachment_id=27534\" class=\"wp-image-27534\" srcset=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-novo-passat-dok.jpg 631w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-novo-passat-dok-300x200.jpg 300w\" sizes=\"(max-width: 631px) 100vw, 631px\" \/><figcaption class=\"blocks-gallery-item__caption\">Reprodu\u00e7\u00e3o AutoPapo<\/figcaption><\/figure><\/li>\n<li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"284\" height=\"177\" src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-passat-antigo-dok.jpg\" alt=\"\" data-id=\"27535\" data-full-url=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-passat-antigo-dok.jpg\" data-link=\"https:\/\/www.despachantedok.com.br\/blog\/?attachment_id=27535\" class=\"wp-image-27535\"\/><figcaption class=\"blocks-gallery-item__caption\">Reprodu\u00e7\u00e3o Car Blog<\/figcaption><\/figure><\/li>\n<\/ul><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-carros-da-volkswagen-mais-vendidos\">Carros da Volkswagen mais vendidos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No Brasil, a Volkswagen reina no ranking de marcas mais vendidas h\u00e1 anos, com modelos que conquistam o cora\u00e7\u00e3o dos consumidores brasileiros por sua qualidade, confiabilidade e custo-benef\u00edcio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre os campe\u00f5es de vendas da marca em 2023, est\u00e3o:<\/p>\n\n\n\n<div class=\"wp-block-advgb-list\"><ul class=\"advgblist-74386418-c29a-43d2-b1f7-27e022454871 advgb-list advgb-list-controls-play\"><li><strong>Volkswagen Polo<\/strong>, com 111.242 novos emplacamentos;<\/li>\n<li><strong>Volkswagen T-Cross<\/strong>, com 72.441 novos emplacamentos;<\/li>\n<li><a href=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/volkswagen-nivus\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Volkswagen Nivus<\/strong><\/a>, com 52.103 novos emplacamentos;<\/li>\n<li><a href=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/volkswagen-virtus\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Volkswagen Virtus<\/strong><\/a>, com 27.094 novos emplacamentos;<\/li>\n<li><strong>Volkswagen Taos<\/strong>, com 15.986 novos emplacamentos.<\/li>\n<\/ul><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"680\" height=\"383\" src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-volkswagen-taos-cidade-dok.jpg\" alt=\"Foto de Volkswagen Taos Cidade | DOK\" class=\"wp-image-27536\" srcset=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-volkswagen-taos-cidade-dok.jpg 680w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-volkswagen-taos-cidade-dok-300x169.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Taos | Reprodu\u00e7\u00e3o VW<\/figcaption><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-saiba-mais-sobre-ve-culos\">Saiba mais sobre ve\u00edculos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ei, Motorista! Se voc\u00ea chegou at\u00e9 aqui, achamos que tamb\u00e9m vai precisar saber disso. Confira:&nbsp;&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-advgb-list\"><ul class=\"advgblist-f39d06fb-64d6-4b0e-a605-feebe97fee80 advgb-list advgb-list-admin-post\"><li><a href=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/volkswagen-up\/\" target=\"_blank\" rel=\"noreferrer noopener\">Volkswagen Up: o compacto que conquistou o Brasil<\/a><\/li>\n<li><a href=\"https:\/\/www.despachantedok.com.br\/blog\/seguro\/latin-ncap\/\" target=\"_blank\" rel=\"noreferrer noopener\">Latin NCAP: como s\u00e3o os testes de seguran\u00e7a para ve\u00edculos?<\/a><\/li>\n<li><a href=\"https:\/\/www.despachantedok.com.br\/blog\/dicas\/consorcio-de-carros\/\" target=\"_blank\" rel=\"noreferrer noopener\">O guia completo do cons\u00f3rcio de carros<\/a><\/li>\n<\/ul><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-modelos-de-volkswagen-dispon-veis-em-2024\">Modelos de Volkswagen dispon\u00edveis em 2024<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A Volkswagen tem uma ampla variedade de modelos para atender a diferentes perfis de consumidores.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea \u00e9 um jovem urbano procurando um carro econ\u00f4mico e tecnol\u00f3gico, uma fam\u00edlia precisando de um SUV espa\u00e7oso e confort\u00e1vel, ou um empres\u00e1rio que valoriza sofistica\u00e7\u00e3o e desempenho, a marca alem\u00e3 tem o modelo perfeito para voc\u00ea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confira a lista dos modelos de carros da Volkswagen dispon\u00edveis zero km hoje:<\/p>\n\n\n\n<div class=\"wp-block-advgb-list\"><ul class=\"advgblist-ec4262fa-f91d-48f8-9024-8894109c189f advgb-list advgb-list-controls-play\"><li><strong>Hatch: <\/strong>Polo e Polo Track;<\/li>\n<li><strong>Sedan:<\/strong> Virtus e <a href=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/volkswagen-jetta\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jetta<\/a>;<\/li>\n<li><strong>SUV:<\/strong> Nivus, Taos, Novo Tiguan Allspace R-Line, ID.4 e T-Cross;<\/li>\n<li><strong>Picape:<\/strong> Nova Saveiro e Amarok;<\/li>\n<li><strong>Minivan:<\/strong> ID.Buzz (Nova Kombi).<\/li>\n<\/ul><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Motorista, para conhecer detalhadamente as caracter\u00edsticas de cada modelo, acesse o <a href=\"https:\/\/www.vw.com.br\/pt\/carros.html\" target=\"_blank\" rel=\"noreferrer noopener\">cat\u00e1logo da Volkswagen no Brasil<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-gallery aligncenter columns-2 is-cropped wp-block-gallery-2\"><ul class=\"blocks-gallery-grid is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"627\" height=\"353\" src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-tiguan-allspace-r-line-dok.jpg\" alt=\"Foto de Tiguan Allspace R-line | DOK\" data-id=\"27537\" class=\"wp-image-27537\" srcset=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-tiguan-allspace-r-line-dok.jpg 627w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-tiguan-allspace-r-line-dok-300x169.jpg 300w\" sizes=\"(max-width: 627px) 100vw, 627px\" \/><figcaption class=\"blocks-gallery-item__caption\">Tiguan Allspace R-line | Reprodu\u00e7ao VW<\/figcaption><\/figure><\/li>\n<li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"630\" height=\"347\" src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-packshot-azul-dusk-moonstone-eletrico-dok.jpg\" alt=\"\" data-id=\"27538\" data-full-url=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-packshot-azul-dusk-moonstone-eletrico-dok.jpg\" data-link=\"https:\/\/www.despachantedok.com.br\/blog\/?attachment_id=27538\" class=\"wp-image-27538\" srcset=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-packshot-azul-dusk-moonstone-eletrico-dok.jpg 630w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-packshot-azul-dusk-moonstone-eletrico-dok-300x165.jpg 300w\" sizes=\"(max-width: 630px) 100vw, 630px\" \/><figcaption class=\"blocks-gallery-item__caption\">ID.4 | Reprodu\u00e7\u00e3o VW<\/figcaption><\/figure><\/li>\n<\/ul><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-lan-amentos-da-volkswagen-o-que-vem-por-a\">Lan\u00e7amentos da Volkswagen: o que vem por a\u00ed<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A Volkswagen segue inovando e promete um futuro repleto de <a href=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/lancamentos-carros\/\" target=\"_blank\" rel=\"noreferrer noopener\">novidades para o mercado automotivo brasileiro<\/a>, com foco em eletrifica\u00e7\u00e3o, conectividade e tecnologias aut\u00f4nomas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre os destaques, podemos esperar:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-nova-amarok\">Nova Amarok<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A reestiliza\u00e7\u00e3o da Amarok, que seguir\u00e1 um caminho diferente da vers\u00e3o vendida em outros mercados, ser\u00e1 fabricada pela VW na Argentina e manter\u00e1 a plataforma e carroceria atuais, um projeto j\u00e1 consolidado h\u00e1 13 anos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m do visual dianteiro atualizado, a nova Amarok sul-americana ter\u00e1 interior repaginado e novas tecnologias. O motor V6 turbodiesel de 258 cv e 59,1 kgfm de torque continuar\u00e1 presente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-novo-t-cross\">Novo T-Cross<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O Volkswagen T-Cross deve passar por seu primeiro facelift no Brasil no terceiro trimestre de 2024.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nessa nova vers\u00e3o, o visual do T-Cross seguir\u00e1 o padr\u00e3o europeu, com interior atualizado, al\u00e9m de um novo volante com comandos touch e a central multim\u00eddia VW Play.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"628\" height=\"348\" src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-t-cross-banner-externa-dok.jpg\" alt=\"Foto de T-Cross | DOK\" class=\"wp-image-27539\" srcset=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-t-cross-banner-externa-dok.jpg 628w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-t-cross-banner-externa-dok-300x166.jpg 300w\" sizes=\"(max-width: 628px) 100vw, 628px\" \/><figcaption>Reprodu\u00e7\u00e3o VW<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-projeto-vw246\">Projeto VW246<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O novo SUV da VW, menor que o Nivus e o T-Cross, \u00e9 conhecido como &#8220;Novo Gol&#8221;.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com propor\u00e7\u00f5es compactas, esse modelo competir\u00e1 com o Fiat Pulse e o futuro Renault Kardian e tem produ\u00e7\u00e3o prevista para em janeiro de 2025 em Taubat\u00e9, S\u00e3o Paulo.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao que tudo indica, o modelo ser\u00e1 revelado no Sal\u00e3o do Autom\u00f3vel de S\u00e3o Paulo em novembro de 2024. Por aqui, estamos ansiosos, e voc\u00ea, Motorista?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-novo-nivus\">Novo Nivus<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A Volkswagen deve apresentar no segundo trimestre de 2025 a primeira reestiliza\u00e7\u00e3o do Nivus. Com um visual atualizado, o SUV cup\u00ea se diferenciar\u00e1 ainda mais do T-Cross e competir\u00e1 diretamente com o Fiat Fastback.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-nivus-volkswagen-dok.jpg\" alt=\"Foto de Novo Nivus | DOK\" class=\"wp-image-27540\" srcset=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-nivus-volkswagen-dok.jpg 960w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-nivus-volkswagen-dok-300x169.jpg 300w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-nivus-volkswagen-dok-768x432.jpg 768w, https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/foto-nivus-volkswagen-dok-903x508.jpg 903w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption>Nivus atual | Reprodu\u00e7\u00e3o VW<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-golf-r\">Golf-R<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A VW pode trazer de volta ao Brasil o Golf, mas s\u00f3 na vers\u00e3o esportiva R, para competir com o Honda Civic Type R e o Toyota GR Corolla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por enquanto, s\u00e3o apenas rumores \u2013 e fortes! \u2013, por\u00e9m nada confirmado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclus-o\">Conclus\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A Volkswagen \u00e9 sin\u00f4nimo de tradi\u00e7\u00e3o, inova\u00e7\u00e3o e tecnologia. Ao longo de sua hist\u00f3ria, a marca se adaptou \u00e0s mudan\u00e7as do mercado e \u00e0s necessidades dos consumidores, oferecendo carros confi\u00e1veis, seguros e que proporcionam uma experi\u00eancia de dire\u00e7\u00e3o prazerosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a chegada da era da eletrifica\u00e7\u00e3o e das tecnologias aut\u00f4nomas, a Volkswagen promete seguir na vanguarda da ind\u00fastria automotiva, sempre buscando solu\u00e7\u00f5es para um futuro mais sustent\u00e1vel e conectado, dentro do seu projeto \u201cAcelera VW\u201d, em curso desde 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gostou do conte\u00fado? Ent\u00e3o, temos certeza que vai adorar conhecer o <a href=\"https:\/\/www.despachantedok.com.br\/blog\/\" target=\"_blank\" rel=\"noreferrer noopener\">nosso blog<\/a>. Para ficar por dentro de tudo o que acontece no mundo automotivo, acompanhe-nos nas redes sociais <a href=\"https:\/\/www.instagram.com\/dokdespachante\/?__coig_restricted=1\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>, <a href=\"https:\/\/web.facebook.com\/DOKDespachante?_rdc=1&amp;_rdr\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>, <a href=\"https:\/\/www.youtube.com\/@dokoficial\" target=\"_blank\" rel=\"noreferrer noopener\">YouTube<\/a>, <a href=\"https:\/\/www.tiktok.com\/@despachantedok\" target=\"_blank\" rel=\"noreferrer noopener\">TikTok<\/a> e <a href=\"https:\/\/br.linkedin.com\/company\/despachantedok\" target=\"_blank\" rel=\"noreferrer noopener\">LinkedIn<\/a>.&nbsp;<\/p>\n\n\n\n<p class=\"has-luminous-vivid-amber-color has-text-color wp-block-paragraph\"><em><strong>Tags<\/strong>: melhores carros da volkswagen, carros da volkswagen 2024, carros populares da volkswagen<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-perguntas-frequentes-sobre-os-carros-da-volkswagen\">Perguntas frequentes sobre os carros da Volkswagen<\/h2>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1718034061233\"><strong class=\"schema-faq-question\">Quais s\u00e3o todos os carros da Volkswagen?<\/strong> <p class=\"schema-faq-answer\">Atualmente, o cat\u00e1logo da Volkswagen no Brasil conta com os modelos Polo, Polo Track, Virtus, Jetta, Nivus, Taos, Novo Tiguan Allspace R-Line, ID.4 (somente por assinatura), T-Cross, Nova Saveiro, Amarok\u00a0 e a ID.Buzz (Nova Kombi).<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1718034061970\"><strong class=\"schema-faq-question\">Quais s\u00e3o os carros da Volkswagen mais baratos?<\/strong> <p class=\"schema-faq-answer\">No mercado de zero km, os carros da Volkswagen mais baratos s\u00e3o os modelos de entrada do Polo e Polo Track, com pre\u00e7os a partir de R$ 87 mil.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1718034062618\"><strong class=\"schema-faq-question\">Quais s\u00e3o os carros mais vendidos da Volkswagen?<\/strong> <p class=\"schema-faq-answer\">Os carros da Volkswagen mais vendidos da hist\u00f3ria da montadora s\u00e3o: Gol, com mais de 7 milh\u00f5es de unidades, Fusca, com mais de 1,8 milh\u00e3o de unidades e Voyage, com mais de 1,6 milh\u00e3o de unidades.<\/p> <\/div> <\/div>\n<style class=\"advgb-styles-renderer\">.wp-block-advgb-list ul.advgblist-74386418-c29a-43d2-b1f7-27e022454871 > li{font-size:16px;}.wp-block-advgb-list ul.advgblist-74386418-c29a-43d2-b1f7-27e022454871 > li{padding-left:18px;margin-left:0;}.wp-block-advgb-list ul.advgblist-74386418-c29a-43d2-b1f7-27e022454871 > li:before{font-size:16px;color:#cf2e2e;line-height:18px;margin:2px;padding:2px;margin-left:-20px}.wp-block-advgb-list ul.advgblist-f39d06fb-64d6-4b0e-a605-feebe97fee80 > li{font-size:16px;}.wp-block-advgb-list ul.advgblist-f39d06fb-64d6-4b0e-a605-feebe97fee80 > li{padding-left:18px;margin-left:0;}.wp-block-advgb-list ul.advgblist-f39d06fb-64d6-4b0e-a605-feebe97fee80 > li:before{font-size:16px;color:#cf2e2e;line-height:18px;margin:2px;padding:2px;margin-left:-20px}.wp-block-advgb-list ul.advgblist-ec4262fa-f91d-48f8-9024-8894109c189f > li{font-size:16px;}.wp-block-advgb-list ul.advgblist-ec4262fa-f91d-48f8-9024-8894109c189f > li{padding-left:18px;margin-left:0;}.wp-block-advgb-list ul.advgblist-ec4262fa-f91d-48f8-9024-8894109c189f > li:before{font-size:16px;color:#cf2e2e;line-height:18px;margin:2px;padding:2px;margin-left:-20px}<\/style>","protected":false},"excerpt":{"rendered":"<p>Salve, Motorista! Os carros da Volkswagen s\u00e3o uma mistura \u00fanica de tradi\u00e7\u00e3o e inova\u00e7\u00e3o. Com um legado de oito d\u00e9cadas na ind\u00fastria automotiva, a Volkswagen se consolidou como uma das maiores montadoras do planeta.&nbsp; Seus cl\u00e1ssicos modelos que moldaram a hist\u00f3ria da marca, at\u00e9 os mais recentes lan\u00e7amentos, continuam a surpreender e encantar entusiastas e [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":27541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_title":"Carros da Volkswagen: acompanhe a jornada do passado ao futuro | DOK","_yoast_wpseo_metadesc":"Clique e explore a hist\u00f3ria e inova\u00e7\u00e3o dos carros da Volkswagen, desde os cl\u00e1ssicos ic\u00f4nicos at\u00e9 os lan\u00e7amentos que vem por a\u00ed!","advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_glsr_average":5,"_glsr_ranking":3.9285714285714,"_glsr_reviews":4,"lazy_load_responsive_images_disabled":false,"footnotes":""},"categories":[131],"tags":[],"class_list":["post-27530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veiculo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Carros da Volkswagen: acompanhe a jornada do passado ao futuro | DOK<\/title>\n<meta name=\"description\" content=\"Clique e explore a hist\u00f3ria e inova\u00e7\u00e3o dos carros da Volkswagen, desde os cl\u00e1ssicos ic\u00f4nicos at\u00e9 os lan\u00e7amentos que vem por a\u00ed!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carros da Volkswagen: entre cl\u00e1ssicos e lan\u00e7amentos\" \/>\n<meta property=\"og:description\" content=\"Clique e explore a hist\u00f3ria e inova\u00e7\u00e3o dos carros da Volkswagen, desde os cl\u00e1ssicos ic\u00f4nicos at\u00e9 os lan\u00e7amentos que vem por a\u00ed!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/\" \/>\n<meta property=\"og:site_name\" content=\"Acesse o Blog e conhe\u00e7a todos os nossos artigos | DOK Despachante\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/DOKDespachante\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-10T17:02:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-10T17:02:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/capa-carros-da-volkswagen-acompanhe-a-jornada-do-passado-ao-futuro-dok.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"254\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheus Packs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheus Packs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/\"},\"author\":{\"name\":\"Matheus Packs\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/person\/2d72f275cc5c082a7a83df99581e4605\"},\"headline\":\"Carros da Volkswagen: entre cl\u00e1ssicos e lan\u00e7amentos\",\"datePublished\":\"2024-06-10T17:02:31+00:00\",\"dateModified\":\"2024-06-10T17:02:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/\"},\"wordCount\":1482,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/capa-carros-da-volkswagen-acompanhe-a-jornada-do-passado-ao-futuro-dok.jpg\",\"articleSection\":[\"Ve\u00edculos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#organization\"}},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/\",\"url\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/\",\"name\":\"Carros da Volkswagen: acompanhe a jornada do passado ao futuro | DOK\",\"isPartOf\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/capa-carros-da-volkswagen-acompanhe-a-jornada-do-passado-ao-futuro-dok.jpg\",\"datePublished\":\"2024-06-10T17:02:31+00:00\",\"dateModified\":\"2024-06-10T17:02:33+00:00\",\"description\":\"Clique e explore a hist\u00f3ria e inova\u00e7\u00e3o dos carros da Volkswagen, desde os cl\u00e1ssicos ic\u00f4nicos at\u00e9 os lan\u00e7amentos que vem por a\u00ed!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034061233\"},{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034061970\"},{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034062618\"}],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#primaryimage\",\"url\":\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/capa-carros-da-volkswagen-acompanhe-a-jornada-do-passado-ao-futuro-dok.jpg\",\"contentUrl\":\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/capa-carros-da-volkswagen-acompanhe-a-jornada-do-passado-ao-futuro-dok.jpg\",\"width\":555,\"height\":254,\"caption\":\"Capa Artigo Carros da Volkswagen acompanhe a jornada do passado ao futuro | DOK\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.despachantedok.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ve\u00edculos\",\"item\":\"https:\/\/www.despachantedok.com.br\/blog\/categoria\/veiculo\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carros da Volkswagen: entre cl\u00e1ssicos e lan\u00e7amentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#website\",\"url\":\"https:\/\/www.despachantedok.com.br\/blog\/\",\"name\":\"Not\u00edcias e informa\u00e7\u00f5es do universo veicular - Blog do Dok\",\"description\":\"Fique por dentro de artigos sobre o tr\u00e2nsito brasileiro! Conhe\u00e7a informa\u00e7\u00f5es sobre licenciamento, ipva, multas e muito mais. Acesse agora o Blog do DOK!\",\"publisher\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#organization\"},\"alternateName\":\"Blog do Dok\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.despachantedok.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#organization\",\"name\":\"Dok Despachante\",\"alternateName\":\"Dok\",\"url\":\"https:\/\/www.despachantedok.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/01\/logo-dok_novo_blog.svg\",\"contentUrl\":\"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/01\/logo-dok_novo_blog.svg\",\"width\":284,\"height\":131,\"caption\":\"Dok Despachante\"},\"image\":{\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/DOKDespachante\/\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Pra\u00e7a Frank Speers, 12\",\"addressLocality\":\"Sorocaba\",\"addressRegion\":\"SP\",\"postalCode\":\"18095-020\",\"addressCountry\":\"BR\"},\"email\":\"fale@despachantedok.com.br\",\"telephone\":\"551530422030\",\"legalName\":\"DOK Servi\u00e7os de Pagamentos Ltda.\",\"vatID\":\"27.838.743\/0001-91\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/person\/2d72f275cc5c082a7a83df99581e4605\",\"name\":\"Matheus Packs\",\"description\":\"Formado em Engenharia Civil, Matheus Packs \u00e9 um dos idealizadores e protagonistas na cria\u00e7\u00e3o de um novo modelo de neg\u00f3cio dentro do DOK, onde alavancou os resultados e transformou a empresa em uma pioneira no mercado de despachante online. Focado em estrat\u00e9gias de venda, Matheus \u00e9 apaixonado por inova\u00e7\u00e3o e desburocratiza\u00e7\u00e3o. Por meio do DOK, busca gerar valor aos consumidores, proporcionando simplicidade, facilidade e transpar\u00eancia ao regularizar d\u00e9bitos veiculares, como IPVA, Licenciamento e multas.\",\"url\":\"https:\/\/www.despachantedok.com.br\/blog\/author\/matheus-packs\/\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034061233\",\"position\":1,\"url\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034061233\",\"name\":\"Quais s\u00e3o todos os carros da Volkswagen?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Atualmente, o cat\u00e1logo da Volkswagen no Brasil conta com os modelos Polo, Polo Track, Virtus, Jetta, Nivus, Taos, Novo Tiguan Allspace R-Line, ID.4 (somente por assinatura), T-Cross, Nova Saveiro, Amarok\u00a0 e a ID.Buzz (Nova Kombi).\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034061970\",\"position\":2,\"url\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034061970\",\"name\":\"Quais s\u00e3o os carros da Volkswagen mais baratos?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"No mercado de zero km, os carros da Volkswagen mais baratos s\u00e3o os modelos de entrada do Polo e Polo Track, com pre\u00e7os a partir de R$ 87 mil.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034062618\",\"position\":3,\"url\":\"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034062618\",\"name\":\"Quais s\u00e3o os carros mais vendidos da Volkswagen?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Os carros da Volkswagen mais vendidos da hist\u00f3ria da montadora s\u00e3o: Gol, com mais de 7 milh\u00f5es de unidades, Fusca, com mais de 1,8 milh\u00e3o de unidades e Voyage, com mais de 1,6 milh\u00e3o de unidades.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Carros da Volkswagen: acompanhe a jornada do passado ao futuro | DOK","description":"Clique e explore a hist\u00f3ria e inova\u00e7\u00e3o dos carros da Volkswagen, desde os cl\u00e1ssicos ic\u00f4nicos at\u00e9 os lan\u00e7amentos que vem por a\u00ed!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/","og_locale":"pt_BR","og_type":"article","og_title":"Carros da Volkswagen: entre cl\u00e1ssicos e lan\u00e7amentos","og_description":"Clique e explore a hist\u00f3ria e inova\u00e7\u00e3o dos carros da Volkswagen, desde os cl\u00e1ssicos ic\u00f4nicos at\u00e9 os lan\u00e7amentos que vem por a\u00ed!","og_url":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/","og_site_name":"Acesse o Blog e conhe\u00e7a todos os nossos artigos | DOK Despachante","article_publisher":"https:\/\/facebook.com\/DOKDespachante\/","article_published_time":"2024-06-10T17:02:31+00:00","article_modified_time":"2024-06-10T17:02:33+00:00","og_image":[{"width":555,"height":254,"url":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/capa-carros-da-volkswagen-acompanhe-a-jornada-do-passado-ao-futuro-dok.jpg","type":"image\/jpeg"}],"author":"Matheus Packs","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Matheus Packs","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#article","isPartOf":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/"},"author":{"name":"Matheus Packs","@id":"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/person\/2d72f275cc5c082a7a83df99581e4605"},"headline":"Carros da Volkswagen: entre cl\u00e1ssicos e lan\u00e7amentos","datePublished":"2024-06-10T17:02:31+00:00","dateModified":"2024-06-10T17:02:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/"},"wordCount":1482,"commentCount":0,"publisher":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/capa-carros-da-volkswagen-acompanhe-a-jornada-do-passado-ao-futuro-dok.jpg","articleSection":["Ve\u00edculos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/#organization"}},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/","url":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/","name":"Carros da Volkswagen: acompanhe a jornada do passado ao futuro | DOK","isPartOf":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#primaryimage"},"image":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/capa-carros-da-volkswagen-acompanhe-a-jornada-do-passado-ao-futuro-dok.jpg","datePublished":"2024-06-10T17:02:31+00:00","dateModified":"2024-06-10T17:02:33+00:00","description":"Clique e explore a hist\u00f3ria e inova\u00e7\u00e3o dos carros da Volkswagen, desde os cl\u00e1ssicos ic\u00f4nicos at\u00e9 os lan\u00e7amentos que vem por a\u00ed!","breadcrumb":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034061233"},{"@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034061970"},{"@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034062618"}],"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#primaryimage","url":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/capa-carros-da-volkswagen-acompanhe-a-jornada-do-passado-ao-futuro-dok.jpg","contentUrl":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/capa-carros-da-volkswagen-acompanhe-a-jornada-do-passado-ao-futuro-dok.jpg","width":555,"height":254,"caption":"Capa Artigo Carros da Volkswagen acompanhe a jornada do passado ao futuro | DOK"},{"@type":"BreadcrumbList","@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.despachantedok.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Ve\u00edculos","item":"https:\/\/www.despachantedok.com.br\/blog\/categoria\/veiculo\/"},{"@type":"ListItem","position":3,"name":"Carros da Volkswagen: entre cl\u00e1ssicos e lan\u00e7amentos"}]},{"@type":"WebSite","@id":"https:\/\/www.despachantedok.com.br\/blog\/#website","url":"https:\/\/www.despachantedok.com.br\/blog\/","name":"Not\u00edcias e informa\u00e7\u00f5es do universo veicular - Blog do Dok","description":"Fique por dentro de artigos sobre o tr\u00e2nsito brasileiro! Conhe\u00e7a informa\u00e7\u00f5es sobre licenciamento, ipva, multas e muito mais. Acesse agora o Blog do DOK!","publisher":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/#organization"},"alternateName":"Blog do Dok","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.despachantedok.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.despachantedok.com.br\/blog\/#organization","name":"Dok Despachante","alternateName":"Dok","url":"https:\/\/www.despachantedok.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/01\/logo-dok_novo_blog.svg","contentUrl":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/01\/logo-dok_novo_blog.svg","width":284,"height":131,"caption":"Dok Despachante"},"image":{"@id":"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/DOKDespachante\/"],"address":{"@type":"PostalAddress","streetAddress":"Pra\u00e7a Frank Speers, 12","addressLocality":"Sorocaba","addressRegion":"SP","postalCode":"18095-020","addressCountry":"BR"},"email":"fale@despachantedok.com.br","telephone":"551530422030","legalName":"DOK Servi\u00e7os de Pagamentos Ltda.","vatID":"27.838.743\/0001-91"},{"@type":"Person","@id":"https:\/\/www.despachantedok.com.br\/blog\/#\/schema\/person\/2d72f275cc5c082a7a83df99581e4605","name":"Matheus Packs","description":"Formado em Engenharia Civil, Matheus Packs \u00e9 um dos idealizadores e protagonistas na cria\u00e7\u00e3o de um novo modelo de neg\u00f3cio dentro do DOK, onde alavancou os resultados e transformou a empresa em uma pioneira no mercado de despachante online. Focado em estrat\u00e9gias de venda, Matheus \u00e9 apaixonado por inova\u00e7\u00e3o e desburocratiza\u00e7\u00e3o. Por meio do DOK, busca gerar valor aos consumidores, proporcionando simplicidade, facilidade e transpar\u00eancia ao regularizar d\u00e9bitos veiculares, como IPVA, Licenciamento e multas.","url":"https:\/\/www.despachantedok.com.br\/blog\/author\/matheus-packs\/"},{"@type":"Question","@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034061233","position":1,"url":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034061233","name":"Quais s\u00e3o todos os carros da Volkswagen?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Atualmente, o cat\u00e1logo da Volkswagen no Brasil conta com os modelos Polo, Polo Track, Virtus, Jetta, Nivus, Taos, Novo Tiguan Allspace R-Line, ID.4 (somente por assinatura), T-Cross, Nova Saveiro, Amarok\u00a0 e a ID.Buzz (Nova Kombi).","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034061970","position":2,"url":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034061970","name":"Quais s\u00e3o os carros da Volkswagen mais baratos?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"No mercado de zero km, os carros da Volkswagen mais baratos s\u00e3o os modelos de entrada do Polo e Polo Track, com pre\u00e7os a partir de R$ 87 mil.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034062618","position":3,"url":"https:\/\/www.despachantedok.com.br\/blog\/veiculo\/carros-da-volkswagen\/#faq-question-1718034062618","name":"Quais s\u00e3o os carros mais vendidos da Volkswagen?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Os carros da Volkswagen mais vendidos da hist\u00f3ria da montadora s\u00e3o: Gol, com mais de 7 milh\u00f5es de unidades, Fusca, com mais de 1,8 milh\u00e3o de unidades e Voyage, com mais de 1,6 milh\u00e3o de unidades.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"}]}},"author_meta":{"display_name":"Matheus Packs","author_link":"https:\/\/www.despachantedok.com.br\/blog\/author\/matheus-packs\/"},"featured_img":"https:\/\/assets.despachantedok.com.br\/blog\/wp-content\/uploads\/2024\/06\/capa-carros-da-volkswagen-acompanhe-a-jornada-do-passado-ao-futuro-dok-300x137.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.despachantedok.com.br\/blog\/categoria\/veiculo\/\" class=\"advgb-post-tax-term\">Ve\u00edculos<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Ve\u00edculos<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em junho 10, 2024","modified":"Atualizado em junho 10, 2024"},"absolute_dates_time":{"created":"Publicado em junho 10, 2024 2:02 pm","modified":"Atualizado em junho 10, 2024 2:02 pm"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/posts\/27530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/comments?post=27530"}],"version-history":[{"count":2,"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/posts\/27530\/revisions"}],"predecessor-version":[{"id":27563,"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/posts\/27530\/revisions\/27563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/media\/27541"}],"wp:attachment":[{"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/media?parent=27530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/categories?post=27530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.despachantedok.com.br\/blog\/wp-json\/wp\/v2\/tags?post=27530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}